                        {"id":11460,"date":"2025-05-27T09:35:33","date_gmt":"2025-05-27T08:35:33","guid":{"rendered":"https:\/\/www.tiendanimal.pt\/blog\/?p=11460"},"modified":"2025-05-27T09:35:35","modified_gmt":"2025-05-27T08:35:35","slug":"acaros-em-caes","status":"publish","type":"post","link":"https:\/\/www.tiendanimal.pt\/blog\/acaros-em-caes\/","title":{"rendered":"\u00c1caros em c\u00e3es: Um guia completo de preven\u00e7\u00e3o e tratamento"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.tiendanimal.pt\/blog\/acaros-em-caes\/#O_que_sao_os_acaros_nos_caes_e_porque_e_que_sao_um_problema\" >O que s\u00e3o os \u00e1caros nos c\u00e3es e porque \u00e9 que s\u00e3o um problema?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.tiendanimal.pt\/blog\/acaros-em-caes\/#Como_posso_saber_se_o_meu_cao_tem_acaros\" >Como posso saber se o meu c\u00e3o tem \u00e1caros?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.tiendanimal.pt\/blog\/acaros-em-caes\/#Acaros_nas_orelhas_dos_caes_detecao_e_prevencao\" >\u00c1caros nas orelhas dos c\u00e3es: dete\u00e7\u00e3o e preven\u00e7\u00e3o<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.tiendanimal.pt\/blog\/acaros-em-caes\/#Como_prevenir_os_acaros_nos_caes\" >Como prevenir os \u00e1caros nos c\u00e3es<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.tiendanimal.pt\/blog\/acaros-em-caes\/#Como_eliminar_os_acaros_no_meu_cao\" >Como eliminar os \u00e1caros no meu c\u00e3o<\/a><\/li><\/ul><\/nav><\/div>\n\n<p><strong>Os \u00e1caros nos c\u00e3es <\/strong>podem tornar-se um problema grave se n\u00e3o forem detetados a tempo. Estes pequenos parasitas podem infestar a pele e as orelhas do seu c\u00e3o, causando comich\u00e3o, irrita\u00e7\u00e3o e outros problemas dermatol\u00f3gicos. Mas n\u00e3o se preocupe: com <strong>uma boa preven\u00e7\u00e3o e cuidados adequados<\/strong>, pode evitar que o seu c\u00e3o sofra de uma infesta\u00e7\u00e3o deste tipo.<\/p>\n\n\n\n<p>Aqui encontrar\u00e1 tudo o que precisa de saber sobre <strong>os \u00e1caros nos<\/strong> <strong>c\u00e3es, como os reconhecer e, <\/strong>acima de tudo, como os prevenir. Vamos l\u00e1!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_que_sao_os_acaros_nos_caes_e_porque_e_que_sao_um_problema\"><\/span>O que s\u00e3o os \u00e1caros nos c\u00e3es e porque \u00e9 que s\u00e3o um problema?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>Os \u00e1caros s\u00e3o parasitas microsc\u00f3picos <\/strong>que se alimentam da pele, da cera dos ouvidos ou do sangue dos c\u00e3es. Alguns podem estar presentes em pequenas quantidades sem causar danos, mas outros podem multiplicar-se incontrolavelmente e<strong> <\/strong>causar <strong>graves problemas de pele.<\/strong><\/p>\n\n\n\n<p>Existem diferentes tipos de \u00e1caros que atacam os c\u00e3es e os mais comuns s\u00e3o os seguintes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><em>Otodectes cynotis <\/em><\/strong>(\u00e1caro do ouvido),<\/li>\n\n\n\n<li><strong><em>Sarcoptes scabiei <\/em><\/strong>(\u00e1caro da sarna sarc\u00f3tica)<\/li>\n\n\n\n<li>e <strong><em>Demodex canis <\/em><\/strong>(\u00e1caro demod\u00e9cico).<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>No entanto, se o sistema imunit\u00e1rio do seu c\u00e3o estiver enfraquecido, estes \u00e1caros podem <strong>multiplicar-se e causar uma infe\u00e7\u00e3o.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td><style>.ds-icon-mobile{display:none;}@media screen and (max-width: 767px) {.ds-icon-desktop{display:none;}.ds-icon-mobile{display:inline;}}<\/style><span style=\"color:#78b800\"><svg class=\"bi d-none d-sm-inline-block d-md-inline-block d-lg-inline-block d-xl-inline-block ds-icon-desktop\" width=\"35\" height=\"35\" fill=\"#78b800\"><use xlink:href=\"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#info-circle\"\/><\/svg><svg class=\"bi d-inline-block d-sm-none d-md-none d-lg-none d-xl-none ds-icon-mobile\" width=\"35\" height=\"35\" fill=\"#78b800\"><use xlink:href=\"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#info-circle\"\/><\/svg><\/span><\/td><td>Alguns fatores podem tornar o seu c\u00e3o mais suscet\u00edvel aos \u00e1caros, como a <strong>idade <\/strong>(os cachorros e os c\u00e3es mais velhos s\u00e3o mais suscet\u00edveis), um <strong>sistema imunit\u00e1rio enfraquecido<\/strong>, <strong>falta de higiene ou contacto com outros animais infetados<\/strong>.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_posso_saber_se_o_meu_cao_tem_acaros\"><\/span>Como posso saber se o meu c\u00e3o tem \u00e1caros?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u00c9 importante detetar atempadamente os \u00e1caros para evitar complica\u00e7\u00f5es. Eis alguns sinais de alerta:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sintomas vis\u00edveis dos \u00e1caros na pele: <\/strong>os \u00e1caros podem causar <strong>vermelhid\u00e3o, comich\u00e3o intensa, descama\u00e7\u00e3o, forma\u00e7\u00e3o de crostas e perda de pelo <\/strong>nas \u00e1reas afetadas. Em alguns casos, pode at\u00e9 ver pequenas protuber\u00e2ncias ou borbulhas na pele do seu c\u00e3o.<\/li>\n\n\n\n<li><strong>Comportamentos invulgares que indicam comich\u00e3o: <\/strong>se o seu c\u00e3o est\u00e1 constantemente a<strong> co\u00e7ar-se, a lamber-se<\/strong> <strong>ou a esfregar-se<\/strong>, pode estar a sofrer de comich\u00e3o causada por \u00e1caros<strong>. <\/strong>O seu c\u00e3o pode tamb\u00e9m estar <strong>inquieto, irrit\u00e1vel <\/strong>ou ter dificuldade em dormir.<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Se notar algum destes sintomas, \u00e9 importante <strong>agir rapidamente para evitar que o problema se agrave.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Acaros_nas_orelhas_dos_caes_detecao_e_prevencao\"><\/span>\u00c1caros nas orelhas dos c\u00e3es: dete\u00e7\u00e3o e preven\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Os \u00e1caros nas orelhas s\u00e3o particularmente problem\u00e1ticos e podem levar a otites se n\u00e3o forem tratados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sinais espec\u00edficos de \u00e1caros nas orelhas<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Abana frequentemente a cabe\u00e7a.<\/li>\n\n\n\n<li>Co\u00e7a intensamente as orelhas.<\/li>\n\n\n\n<li>Produ\u00e7\u00e3o excessiva de cera escura nos ouvidos.<\/li>\n\n\n\n<li>Mau cheiro nos ouvidos.<\/li>\n\n\n\n<li>Inflama\u00e7\u00e3o da zona auricular.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Limpeza e cuidados preventivos das orelhas<\/h3>\n\n\n\n<p>Para evitar os \u00e1caros nas orelhas do seu c\u00e3o, \u00e9 importante que mantenha uma boa higiene. Verifique regularmente as orelhas do seu c\u00e3o e utilize <strong><a href=\"https:\/\/www.tiendanimal.pt\/caes\/saude-e-higiene\/produtos-de-cuidados-para-os-ouvidos-dos-caes\/\" target=\"_blank\" rel=\"noreferrer noopener\">produtos para as limpar<\/a><\/strong>. Evite <strong>a acumula\u00e7\u00e3o de humidade <\/strong>nos ouvidos <strong>e n\u00e3o utilize cotonetes<\/strong>, pois estes podem danificar o canal auditivo.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n  <style>\n  .product-container{\n    cursor:pointer;\n  }\n  a.producto-titulo{\n    font-size: 13px;line-height: 1.2;height: 62px;margin-bottom: 12px;color: #575757;font-weight:400;display:inline-block;overflow:hidden;font-family: \"Poppins\", sans-serif;\n  }\n  .producto .product-container img{\n    max-height: 126px;\n    width: auto;\n    height: auto;\n  }\n  @media (max-width: 480px){\n    a.producto-titulo{\n        font-size: 16px;\n        line-height: 1.3;\n    }\n  }\n  <\/style>\n  <div class=\"clearfix\"><\/div>\n    <div id=\"external-products-56839\" class=\"row external-products producto\" style=\"width:100%; margin:0 auto;\"><div itemprop=\"offers\" itemscope itemtype=\"http:\/\/schema.org\/Offer\" class=\"product-container\" style=\"width:19.4%;margin:0 auto;display:inline-block;\" onclick=\"dataLayer.push({'event':'crosseling_product_click', 'event_name':'crosseling_product_click', 'label':'body', 'link_url':'https:\/\/www.tiendanimal.pt\/psh-solucao-de-limpeza-de-ouvidos-para-gatos\/PSH1820LOT.html', 'category':'Limpeza de ouvidos', 'product_name':'PSH Solu\u00e7\u00e3o de limpeza de ouvidos para gatos'});window.open('https:\/\/www.tiendanimal.pt\/psh-solucao-de-limpeza-de-ouvidos-para-gatos\/PSH1820LOT.html');\">\n      <img decoding=\"async\" src=\"https:\/\/www.tiendanimal.pt\/on\/demandware.static\/-\/Sites-kiwoko-master-catalog\/default\/dw5eec137b\/images\/psh_limpiador_oidos_gato_PSH1820LOT.jpg\" alt=\"PSH Solu\u00e7\u00e3o de limpeza de ouvidos para gatos\" width=\"90%\" \/><a href=\"https:\/\/www.tiendanimal.pt\/psh-solucao-de-limpeza-de-ouvidos-para-gatos\/PSH1820LOT.html\" itemprop=\"name\" class=\"producto-titulo\" data-test=\"test\" target=\"_blank\">PSH Solu\u00e7\u00e3o de limpeza de ouvidos para gatos<\/a>\n      <button class=\"producto-boton\" style=\"width:100%;border-radius:3px;padding:5px;\">Ver produto<\/button><\/div>\n      <div itemprop=\"offers\" itemscope itemtype=\"http:\/\/schema.org\/Offer\" class=\"product-container\" style=\"width:19.4%;margin:0 auto;display:inline-block;\" onclick=\"dataLayer.push({'event':'crosseling_product_click', 'event_name':'crosseling_product_click', 'label':'body', 'link_url':'https:\/\/www.tiendanimal.pt\/artero-aurigel-limpador-de-ouvidos-para-caes\/ARTH640.html', 'category':'Produtos de cuidados para os ouvidos dos c\u00e3es', 'product_name':'Artero Aurigel Limpador de ouvidos para c\u00e3es'});window.open('https:\/\/www.tiendanimal.pt\/artero-aurigel-limpador-de-ouvidos-para-caes\/ARTH640.html');\">\n      <img decoding=\"async\" src=\"https:\/\/www.tiendanimal.pt\/on\/demandware.static\/-\/Sites-kiwoko-master-catalog\/default\/dw8c7dffac\/images\/new_limpiador_perros_artero_o\u00eddos_aurigel_ARTH640_M_2.jpg\" alt=\"Artero Aurigel Limpador de ouvidos para c\u00e3es\" width=\"90%\" \/><a href=\"https:\/\/www.tiendanimal.pt\/artero-aurigel-limpador-de-ouvidos-para-caes\/ARTH640.html\" itemprop=\"name\" class=\"producto-titulo\" data-test=\"test\" target=\"_blank\">Artero Aurigel Limpador de ouvidos para c\u00e3es<\/a>\n      <button class=\"producto-boton\" style=\"width:100%;border-radius:3px;padding:5px;\">Ver produto<\/button><\/div>\n      <div itemprop=\"offers\" itemscope itemtype=\"http:\/\/schema.org\/Offer\" class=\"product-container\" style=\"width:19.4%;margin:0 auto;display:inline-block;\" onclick=\"dataLayer.push({'event':'crosseling_product_click', 'event_name':'crosseling_product_click', 'label':'body', 'link_url':'https:\/\/www.tiendanimal.pt\/francodex-limpador-de-ouvidos-para-animais-de-estimacao\/FRC31140.html', 'category':'Produtos de cuidados para os ouvidos dos c\u00e3es', 'product_name':'Francodex Limpador de Ouvidos para animais de estima\u00e7\u00e3o'});window.open('https:\/\/www.tiendanimal.pt\/francodex-limpador-de-ouvidos-para-animais-de-estimacao\/FRC31140.html');\">\n      <img decoding=\"async\" src=\"https:\/\/www.tiendanimal.pt\/on\/demandware.static\/-\/Sites-kiwoko-master-catalog\/default\/dwce7975cc\/images\/higiene_limpiador_oreja_perro_gato_francodex_FRC31140_M.jpg\" alt=\"Francodex Limpador de Ouvidos para animais de estima\u00e7\u00e3o\" width=\"90%\" \/><a href=\"https:\/\/www.tiendanimal.pt\/francodex-limpador-de-ouvidos-para-animais-de-estimacao\/FRC31140.html\" itemprop=\"name\" class=\"producto-titulo\" data-test=\"test\" target=\"_blank\">Francodex Limpador de Ouvidos para animais de estima\u00e7\u00e3o<\/a>\n      <button class=\"producto-boton\" style=\"width:100%;border-radius:3px;padding:5px;\">Ver produto<\/button><\/div>\n      <div itemprop=\"offers\" itemscope itemtype=\"http:\/\/schema.org\/Offer\" class=\"product-container\" style=\"width:19.4%;margin:0 auto;display:inline-block;\" onclick=\"dataLayer.push({'event':'crosseling_product_click', 'event_name':'crosseling_product_click', 'label':'body', 'link_url':'https:\/\/www.tiendanimal.pt\/125-ml-calier-adolac-limpador-de-ouvidos-para-caes-e-gatos\/CLR10784.html', 'category':'Limpeza de ouvidos', 'product_name':'125 ml Calier Adolac Limpador de ouvidos para c\u00e3es e gatos'});window.open('https:\/\/www.tiendanimal.pt\/125-ml-calier-adolac-limpador-de-ouvidos-para-caes-e-gatos\/CLR10784.html');\">\n      <img decoding=\"async\" src=\"https:\/\/www.tiendanimal.pt\/on\/demandware.static\/-\/Sites-kiwoko-master-catalog\/default\/dw81534485\/images\/Calier_Adolac_limpiador_de_oidos_perros_y_gatos__CLR10784.jpg\" alt=\"125 ml Calier Adolac Limpador de ouvidos para c\u00e3es e gatos\" width=\"90%\" \/><a href=\"https:\/\/www.tiendanimal.pt\/125-ml-calier-adolac-limpador-de-ouvidos-para-caes-e-gatos\/CLR10784.html\" itemprop=\"name\" class=\"producto-titulo\" data-test=\"test\" target=\"_blank\">125 ml Calier Adolac Limpador de ouvidos para c\u00e3es e gatos<\/a>\n      <button class=\"producto-boton\" style=\"width:100%;border-radius:3px;padding:5px;\">Ver produto<\/button><\/div>\n      <div itemprop=\"offers\" itemscope itemtype=\"http:\/\/schema.org\/Offer\" class=\"product-container\" style=\"width:19.4%;margin:0 auto;display:inline-block;\" onclick=\"dataLayer.push({'event':'crosseling_product_click', 'event_name':'crosseling_product_click', 'label':'body', 'link_url':'https:\/\/www.tiendanimal.pt\/menforsan-produto-de-limpeza-de-ouvidos-para-caes-e-gatos\/MENM0365.html', 'category':'Produtos de cuidados para os ouvidos dos c\u00e3es', 'product_name':'Menforsan Produto de Limpeza de Ouvidos para c\u00e3es e gatos'});window.open('https:\/\/www.tiendanimal.pt\/menforsan-produto-de-limpeza-de-ouvidos-para-caes-e-gatos\/MENM0365.html');\">\n      <img decoding=\"async\" src=\"https:\/\/www.tiendanimal.pt\/on\/demandware.static\/-\/Sites-kiwoko-master-catalog\/default\/dw2eaf2a5b\/images\/limpiador_otico_perros_gatos_menforsan_MENM0365_M.jpg\" alt=\"Menforsan Produto de Limpeza de Ouvidos para c\u00e3es e gatos\" width=\"90%\" \/><a href=\"https:\/\/www.tiendanimal.pt\/menforsan-produto-de-limpeza-de-ouvidos-para-caes-e-gatos\/MENM0365.html\" itemprop=\"name\" class=\"producto-titulo\" data-test=\"test\" target=\"_blank\">Menforsan Produto de Limpeza de Ouvidos para c\u00e3es e gatos<\/a>\n      <button class=\"producto-boton\" style=\"width:100%;border-radius:3px;padding:5px;\">Ver produto<\/button><\/div>\n      <\/div>\n    <br>\n    <div class=\"clearfix\"><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_prevenir_os_acaros_nos_caes\"><\/span>Como prevenir os \u00e1caros nos c\u00e3es<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A preven\u00e7\u00e3o \u00e9 a melhor arma contra os \u00e1caros. Eis algumas medidas importantes:<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-base-3-background-color has-background\">Higiene e escovagem regulares:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Escove o seu c\u00e3o regularmente com um <strong><a href=\"https:\/\/www.tiendanimal.pt\/caes\/antiparasitarios-e-repelentes\/champos-desparasitantes-para-caes\/\" target=\"_blank\" rel=\"noreferrer noopener\">champ\u00f4 antiparasit\u00e1rio<\/a> e escove o pelo <\/strong>para remover o subpelo e a sujidade que podem abrigar os \u00e1caros.<\/li>\n<\/ul>\n\n\n    <style>\n        .product-container{\n            cursor:pointer;\n        }\n        a.producto-titulo{\n            font-size: 13px;line-height: 1.2;height: 62px;margin-bottom: 12px;color: #575757;font-weight:400;display:inline-block;overflow:hidden;font-family: \"Poppins\", sans-serif;\n        }\n        .producto .product-container img{\n            max-height: 126px;\n            width: auto;\n            height: auto;\n        }\n\t.center-product-flex{\n            display:flex;justify-content:center;\n        }\n        .center-product-flex .product-container{\n            max-height: 236px;\n        }\n\t.order-0{\n            -ms-flex-order:0;order:0;\n        }\n        .order-1{\n            -ms-flex-order:1;order:1;\n        }\n        .order-2{\n            -ms-flex-order:2;order:2;\n        }\n        .order-3{\n            -ms-flex-order:3;order:3;\n        }\n        .order-4{\n            -ms-flex-order:4;order:4;\n        }\n        .order-5{\n            -ms-flex-order:5;order:5;\n        }\n        .order-6{\n            -ms-flex-order:6;order:6;\n        }\n        @media (max-width: 480px){\n            a.producto-titulo{\n                font-size: 16px;\n                line-height: 1.3;\n            }\n        }\n    <\/style>\n    <div class=\"clearfix\"><\/div>\n        <div id=\"external-products-YES36808_M\" class=\"row external-products producto  center-product-flex \" style=\"width:100%; margin:0 auto;display: flex;\">\n            <img decoding=\"async\" id=\"load-products-YES36808_M\" src=\"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/themes\/astra-child-ta\/loading.gif\" width=\"50px\">\n        <\/div>\n    <div class=\"clearfix\"><\/div>\n        <script>\n        id_products = \"YES36808_M\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n        var final_products = 0;\n        var num_total_products = all_ids.length;\n        if(!feed){\n            var feed = \"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/themes\/astra-child-ta\/feed-channable.xml\";\n            var request = new XMLHttpRequest();\n            request.open(\"GET\", feed, false);\n            request.send();\n            var xmlFromUrl = request.responseXML;\n            var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n        var div_max = 97 \/ num_total_products;\n        var width;\n        if(num_total_products < 2){\n            width = \"auto;margin:0 auto;\";\n        }else if(num_total_products < 3){\n            width = \"240px;margin:0 auto;display:inline-block;\";\n        }else{\n            width = div_max+\"%;margin:0 auto;display:inline-block\";\n        }\n\n        var products_found = 0;\n\t    product_id_found = [];\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n\t\t        if (product_id_found.includes(item.getElementsByTagName(\"g:item_group_id\")[0].textContent)) {\n                } else {\n                    if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                        not_found_products = 0;\n                        id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                        var link = item.getElementsByTagName(\"link\")[0].textContent;\n                        var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                        var title = item.getElementsByTagName(\"title\")[0].textContent;\n                        var category = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || \"\";\n                        var product = '<div itemprop=\"offers\" itemscope itemtype=\"http:\/\/schema.org\/Offer\" class=\"product-container order-'+index+'\" style=\"width:'+width+'\" onclick=\"dataLayer.push({\\'event\\':\\'crosseling_product_click\\', \\'event_name\\':\\'crosseling_product_click\\', \\'action\\':\\'body\\', \\'category\\':\\''+category+'\\', \\'link_text\\':\\'\u00a1Lo quiero!\\', \\'link_url\\': \\''+link+'\\', \\'product_name\\': \\''+title+'\\'});window.open(\\''+link+'\\');\"><img '+image_link+' alt=\"'+title+'\" width=\"90%\" \/><a href=\"'+link+'\" itemprop=\"name\" class=\"producto-titulo\" data-test=\"test\"  target=\"_blank\">'+title+'<\/a><button class=\"producto-boton\" style=\"width:100%;border-radius:3px;padding:5px;\">Ver produto<\/button><\/div>';\n                        var grid_div = document.getElementById(\"external-products-YES36808_M\");\n                        grid_div.innerHTML += product;\n                        products_found++;\n                        product_id_found.push(item.getElementsByTagName(\"g:item_group_id\")[0].textContent);\n                    }\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-YES36808_M\").style.display = \"none\";\n        <\/script>\n    \n\n\n\n<h3 class=\"wp-block-heading has-base-3-background-color has-background\">Produtos antiparasit\u00e1rios recomendados:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Existem v\u00e1rios <strong><a href=\"https:\/\/www.tiendanimal.pt\/caes\/antiparasitarios-e-repelentes\/\" target=\"_blank\" rel=\"noreferrer noopener\">produtos antiparasit\u00e1rios<\/a> <\/strong>no mercado, como <strong>pipetas e coleiras<\/strong>, que podem ajudar a prevenir infesta\u00e7\u00f5es por \u00e1caros<strong>. Consulte o seu veterin\u00e1rio <\/strong>para lhe recomendar o melhor produto para o seu c\u00e3o.<\/li>\n<\/ul>\n\n\n    <style>\n        .product-container{\n            cursor:pointer;\n        }\n        a.producto-titulo{\n            font-size: 13px;line-height: 1.2;height: 62px;margin-bottom: 12px;color: #575757;font-weight:400;display:inline-block;overflow:hidden;font-family: \"Poppins\", sans-serif;\n        }\n        .producto .product-container img{\n            max-height: 126px;\n            width: auto;\n            height: auto;\n        }\n\t.center-product-flex{\n            display:flex;justify-content:center;\n        }\n        .center-product-flex .product-container{\n            max-height: 236px;\n        }\n\t.order-0{\n            -ms-flex-order:0;order:0;\n        }\n        .order-1{\n            -ms-flex-order:1;order:1;\n        }\n        .order-2{\n            -ms-flex-order:2;order:2;\n        }\n        .order-3{\n            -ms-flex-order:3;order:3;\n        }\n        .order-4{\n            -ms-flex-order:4;order:4;\n        }\n        .order-5{\n            -ms-flex-order:5;order:5;\n        }\n        .order-6{\n            -ms-flex-order:6;order:6;\n        }\n        @media (max-width: 480px){\n            a.producto-titulo{\n                font-size: 16px;\n                line-height: 1.3;\n            }\n        }\n    <\/style>\n    <div class=\"clearfix\"><\/div>\n        <div id=\"external-products-MDC41260_M\" class=\"row external-products producto \" style=\"width:100%; margin:0 auto;display: flex;\">\n            <img decoding=\"async\" id=\"load-products-MDC41260_M\" src=\"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/themes\/astra-child-ta\/loading.gif\" width=\"50px\">\n        <\/div>\n    <div class=\"clearfix\"><\/div>\n        <script>\n        id_products = \"MDC41260_M,MDCCA755843ASPZ1_M,BAY83883961_M,BAY4488389_M,CEVC66150D_M\";\n        id_products = id_products.replace(\/\\s\/g, '');\n        var all_ids = id_products.split(\",\");\n        var not_found_products = 1;\n        var not_found_img_product = 0;\n        var ramdom_id = Math.round(Math.random() * 10000);\n        var grid = '12';\n        var final_products = 0;\n        var num_total_products = all_ids.length;\n        if(!feed){\n            var feed = \"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/themes\/astra-child-ta\/feed-channable.xml\";\n            var request = new XMLHttpRequest();\n            request.open(\"GET\", feed, false);\n            request.send();\n            var xmlFromUrl = request.responseXML;\n            var items = xmlFromUrl.getElementsByTagName(\"item\");\n        }\n        var div_max = 97 \/ num_total_products;\n        var width;\n        if(num_total_products < 2){\n            width = \"auto;margin:0 auto;\";\n        }else if(num_total_products < 3){\n            width = \"240px;margin:0 auto;display:inline-block;\";\n        }else{\n            width = div_max+\"%;margin:0 auto;display:inline-block\";\n        }\n\n        var products_found = 0;\n\t    product_id_found = [];\n        for (var item of items) {\n            all_ids.forEach(function(word, index) {\n\t\t        if (product_id_found.includes(item.getElementsByTagName(\"g:item_group_id\")[0].textContent)) {\n                } else {\n                    if(item.getElementsByTagName(\"g:item_group_id\")[0].textContent == word){\n                        not_found_products = 0;\n                        id_products = item.getElementsByTagName(\"g:item_group_id\")[0].textContent;\n                        var link = item.getElementsByTagName(\"link\")[0].textContent;\n                        var image_link = 'src=\"'+item.getElementsByTagName(\"g:image_link\")[0].textContent+'\" ';\n                        var title = item.getElementsByTagName(\"title\")[0].textContent;\n                        var category = item.getElementsByTagName(\"g:custom_label_1\")[0]?.textContent || \"\";\n                        var product = '<div itemprop=\"offers\" itemscope itemtype=\"http:\/\/schema.org\/Offer\" class=\"product-container order-'+index+'\" style=\"width:'+width+'\" onclick=\"dataLayer.push({\\'event\\':\\'crosseling_product_click\\', \\'event_name\\':\\'crosseling_product_click\\', \\'action\\':\\'body\\', \\'category\\':\\''+category+'\\', \\'link_text\\':\\'\u00a1Lo quiero!\\', \\'link_url\\': \\''+link+'\\', \\'product_name\\': \\''+title+'\\'});window.open(\\''+link+'\\');\"><img '+image_link+' alt=\"'+title+'\" width=\"90%\" \/><a href=\"'+link+'\" itemprop=\"name\" class=\"producto-titulo\" data-test=\"test\"  target=\"_blank\">'+title+'<\/a><button class=\"producto-boton\" style=\"width:100%;border-radius:3px;padding:5px;\">Ver produto<\/button><\/div>';\n                        var grid_div = document.getElementById(\"external-products-MDC41260_M\");\n                        grid_div.innerHTML += product;\n                        products_found++;\n                        product_id_found.push(item.getElementsByTagName(\"g:item_group_id\")[0].textContent);\n                    }\n                }\n            });\n            if(products_found == all_ids.length){\n                break;\n            }\n        }\n        document.getElementById(\"load-products-MDC41260_M\").style.display = \"none\";\n        <\/script>\n    \n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td><style>.ds-icon-mobile{display:none;}@media screen and (max-width: 767px) {.ds-icon-desktop{display:none;}.ds-icon-mobile{display:inline;}}<\/style><span style=\"color:#78b800\"><svg class=\"bi d-none d-sm-inline-block d-md-inline-block d-lg-inline-block d-xl-inline-block ds-icon-desktop\" width=\"35\" height=\"35\" fill=\"#78b800\"><use xlink:href=\"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#bug-fill\"\/><\/svg><svg class=\"bi d-inline-block d-sm-none d-md-none d-lg-none d-xl-none ds-icon-mobile\" width=\"35\" height=\"35\" fill=\"#78b800\"><use xlink:href=\"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#bug-fill\"\/><\/svg><\/span><\/td><td><strong>As pipetas e coleiras antiparasit\u00e1rias <\/strong>s\u00e3o essenciais para a elimina\u00e7\u00e3o e preven\u00e7\u00e3o dos \u00e1caros nos c\u00e3es. <strong>Para complementar a prote\u00e7\u00e3o<\/strong>, pode tamb\u00e9m utilizar repelentes. Recomendamos-lhe que leia a nossa sele\u00e7\u00e3o dos <strong><a href=\"https:\/\/www.tiendanimal.pt\/blog\/melhor-repelente-de-insetos-para-caes\/\">melhores repelentes para c\u00e3es<\/a>.<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-base-3-background-color has-background\">Limpeza do ambiente do c\u00e3o:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lave regularmente a roupa de cama<strong>, os brinquedos e os comedouros <\/strong>do seu c\u00e3o<strong>.<\/strong> Aspire e limpe cuidadosamente os locais onde o seu c\u00e3o passa mais tempo, como a cama, o sof\u00e1 e o carro.<\/li>\n<\/ul>\n\n\n  <style>\n  .product-container{\n    cursor:pointer;\n  }\n  a.producto-titulo{\n    font-size: 13px;line-height: 1.2;height: 62px;margin-bottom: 12px;color: #575757;font-weight:400;display:inline-block;overflow:hidden;font-family: \"Poppins\", sans-serif;\n  }\n  .producto .product-container img{\n    max-height: 126px;\n    width: auto;\n    height: auto;\n  }\n  @media (max-width: 480px){\n    a.producto-titulo{\n        font-size: 16px;\n        line-height: 1.3;\n    }\n  }\n  <\/style>\n  <div class=\"clearfix\"><\/div>\n    <div id=\"external-products-57723\" class=\"row external-products producto\" style=\"width:100%; margin:0 auto;\"><div itemprop=\"offers\" itemscope itemtype=\"http:\/\/schema.org\/Offer\" class=\"product-container\" style=\"width:19.4%;margin:0 auto;display:inline-block;\" onclick=\"dataLayer.push({'event':'crosseling_product_click', 'event_name':'crosseling_product_click', 'label':'body', 'link_url':'https:\/\/www.tiendanimal.pt\/tk-pet-home-limpachao-inseticida\/TKP37465.html', 'category':'Casa', 'product_name':'TK-Pet Home Limpach\u00e3o Inseticida'});window.open('https:\/\/www.tiendanimal.pt\/tk-pet-home-limpachao-inseticida\/TKP37465.html');\">\n      <img decoding=\"async\" src=\"https:\/\/www.tiendanimal.pt\/on\/demandware.static\/-\/Sites-kiwoko-master-catalog\/default\/dwa0d19319\/images\/limpiasuelos_hogar_tk_pet_insecticida_TKP37465_M.jpg\" alt=\"TK-Pet Home Limpach\u00e3o Inseticida\" width=\"90%\" \/><a href=\"https:\/\/www.tiendanimal.pt\/tk-pet-home-limpachao-inseticida\/TKP37465.html\" itemprop=\"name\" class=\"producto-titulo\" data-test=\"test\" target=\"_blank\">TK-Pet Home Limpach\u00e3o Inseticida<\/a>\n      <button class=\"producto-boton\" style=\"width:100%;border-radius:3px;padding:5px;\">Ver produto<\/button><\/div>\n      <div itemprop=\"offers\" itemscope itemtype=\"http:\/\/schema.org\/Offer\" class=\"product-container\" style=\"width:19.4%;margin:0 auto;display:inline-block;\" onclick=\"dataLayer.push({'event':'crosseling_product_click', 'event_name':'crosseling_product_click', 'label':'body', 'link_url':'https:\/\/www.tiendanimal.pt\/tk-pet-home-limpachao-desinfetante\/TKP37464.html', 'category':'Limpeza da casa', 'product_name':'TK-Pet Home Limpach\u00e3o Desinfetante'});window.open('https:\/\/www.tiendanimal.pt\/tk-pet-home-limpachao-desinfetante\/TKP37464.html');\">\n      <img decoding=\"async\" src=\"https:\/\/www.tiendanimal.pt\/on\/demandware.static\/-\/Sites-kiwoko-master-catalog\/default\/dw4fd7fe47\/images\/limpiasuelos_hogar_tk_pet_higienizante_TKP37464_M.jpg\" alt=\"TK-Pet Home Limpach\u00e3o Desinfetante\" width=\"90%\" \/><a href=\"https:\/\/www.tiendanimal.pt\/tk-pet-home-limpachao-desinfetante\/TKP37464.html\" itemprop=\"name\" class=\"producto-titulo\" data-test=\"test\" target=\"_blank\">TK-Pet Home Limpach\u00e3o Desinfetante<\/a>\n      <button class=\"producto-boton\" style=\"width:100%;border-radius:3px;padding:5px;\">Ver produto<\/button><\/div>\n      <\/div>\n    <br>\n    <div class=\"clearfix\"><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_eliminar_os_acaros_no_meu_cao\"><\/span>Como eliminar os \u00e1caros no meu c\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Se suspeita que o seu c\u00e3o tem \u00e1caros, \u00e9 importante que <strong>consulte o seu<\/strong> <strong>veterin\u00e1rio <\/strong>para um diagn\u00f3stico preciso e um <strong>tratamento adequado.<\/strong><\/p>\n\n\n\n<p>O seu veterin\u00e1rio poder\u00e1 identificar o tipo de \u00e1caro que est\u00e1 a atacar o seu c\u00e3o e <strong>prescrever o medicamento mais eficaz. <\/strong>Nunca deve automedicar o seu c\u00e3o, pois alguns medicamentos podem ser t\u00f3xicos se utilizados incorretamente.<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td><style>.ds-icon-mobile{display:none;}@media screen and (max-width: 767px) {.ds-icon-desktop{display:none;}.ds-icon-mobile{display:inline;}}<\/style><span style=\"color:#78b800\"><svg class=\"bi d-none d-sm-inline-block d-md-inline-block d-lg-inline-block d-xl-inline-block ds-icon-desktop\" width=\"35\" height=\"35\" fill=\"#78b800\"><use xlink:href=\"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#exclamation-triangle\"\/><\/svg><svg class=\"bi d-inline-block d-sm-none d-md-none d-lg-none d-xl-none ds-icon-mobile\" width=\"35\" height=\"35\" fill=\"#78b800\"><use xlink:href=\"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#exclamation-triangle\"\/><\/svg><\/span><\/td><td>Embora existam <strong>rem\u00e9dios caseiros <\/strong>para tratar os \u00e1caros, a sua efic\u00e1cia n\u00e3o est\u00e1 cientificamente comprovada e podem ser <strong>prejudiciais para o seu c\u00e3o. <\/strong>Por isso, recomendamos que <strong>siga sempre os conselhos do seu veterin\u00e1rio.<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Os \u00e1caros dos c\u00e3es podem ser inc\u00f3modos, mas com <strong>uma boa preven\u00e7\u00e3o e aten\u00e7\u00e3o aos primeiros sintomas<\/strong>, pode manter o seu c\u00e3o longe destes parasitas. A chave \u00e9 a higiene, utilizando produtos adequados e controlos frequentes da pele e dos ouvidos.<\/p>\n<\/blockquote>\n\n\n\n<p>N\u00e3o perca os nossos pr\u00f3ximos artigos, onde encontrar\u00e1 mais informa\u00e7\u00f5es sobre a preven\u00e7\u00e3o e elimina\u00e7\u00e3o de parasitas em c\u00e3es:<\/p>\n\n\n        <div class=\"grid\">\n        <div class=\"grid-sizer\"><\/div>\n                <a href=\"https:\/\/www.tiendanimal.pt\/blog\/desparasitar-caes-adultos-de-quanto-em-quanto-tempo\/\" class=\"ds-analytics-blog-related-posts\" title=\"Guia informativo para desparasitar corretamente um c\u00e3o adulto\">\n            <div class=\"grid-item\">\n                <div style=\"background: url(https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2021\/04\/Desparasitar-caes-adultos-768x512.jpg);background-size:cover;\n                background-position: center;background-repeat: no-repeat;height:230px;\">\n                <\/div>\n                <p class=\"slider-caption\">Guia informativo para desparasitar corretamente um c\u00e3o adulto<\/p>\n            <\/div>\n        <\/a>\n                <a href=\"https:\/\/www.tiendanimal.pt\/blog\/como-remover-uma-carraca\/\" class=\"ds-analytics-blog-related-posts\" title=\"Carra\u00e7as nos c\u00e3es: qual o seu aspeto, quais os sintomas e como remov\u00ea-las corretamente\">\n            <div class=\"grid-item\">\n                <div style=\"background: url(https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2021\/06\/aprenda-a-remover-as-carracas-do-seu-cao-768x512.jpg);background-size:cover;\n                background-position: center;background-repeat: no-repeat;height:230px;\">\n                <\/div>\n                <p class=\"slider-caption\">Carra\u00e7as nos c\u00e3es: qual o seu aspeto, quais os sintomas e como remov\u00ea-las corretamente<\/p>\n            <\/div>\n        <\/a>\n                <a href=\"https:\/\/www.tiendanimal.pt\/blog\/como-tirar-as-pulgas-de-um-cao\/\" class=\"ds-analytics-blog-related-posts\" title=\"Como tirar as pulgas de um c\u00e3o?\">\n            <div class=\"grid-item\">\n                <div style=\"background: url(https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2021\/07\/Como-tirar-as-pulgas-de-um-cao-768x512.jpg);background-size:cover;\n                background-position: center;background-repeat: no-repeat;height:230px;\">\n                <\/div>\n                <p class=\"slider-caption\">Como tirar as pulgas de um c\u00e3o?<\/p>\n            <\/div>\n        <\/a>\n            <\/div>\n    <script src=\"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/themes\/astra-child-ta\/assets\/js\/masonry.pkgd.js\"><\/script>\n    <script type=\"text\/javascript\">\n        var $grid = jQuery('.grid').masonry({\n            itemSelector: '.grid-item',\n            percentPosition: true,\n            columnWidth: '.grid-sizer'\n        });\n    <\/script>\n    \n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#e6f5db\">Se precisar de algo para o seu animal de estima\u00e7\u00e3o, na <a href=\"https:\/\/www.tiendanimal.pt\/\"><strong>Tiendanimal<\/strong> <\/a>queremos ajud\u00e1-lo. <strong><a href=\"https:\/\/www.tiendanimal.pt\/nossas-lojas?showMap=true&amp;horizontalView=true&amp;isForm=true\">Encontre a sua loja mais pr\u00f3xima<\/a><\/strong> ou se preferir, fa\u00e7a a sua encomenda na nossa loja online especializada em produtos para animais de estima\u00e7\u00e3o, e n\u00e3o perca as nossas <strong><a href=\"https:\/\/www.tiendanimal.pt\/promocoes\/\">promo\u00e7\u00f5es!<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 preocupado com o facto de o seu c\u00e3o ter \u00e1caros? Descubra como reconhecer, prevenir e eliminar estes parasitas inc\u00f3modos. Um guia completo com conselhos de especialistas.<\/p>\n","protected":false},"author":40,"featured_media":11461,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3,6],"tags":[207],"class_list":["post-11460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caes","category-cuidados-saude-caes","tag-antiparasitarios","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2025\/05\/acaros-em-caes-prevencao-e-tratamento.jpg",900,600,false],"thumbnail":["https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2025\/05\/acaros-em-caes-prevencao-e-tratamento-150x150.jpg",150,150,true],"medium":["https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2025\/05\/acaros-em-caes-prevencao-e-tratamento-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2025\/05\/acaros-em-caes-prevencao-e-tratamento-768x512.jpg",768,512,true],"large":["https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2025\/05\/acaros-em-caes-prevencao-e-tratamento.jpg",900,600,false],"1536x1536":["https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2025\/05\/acaros-em-caes-prevencao-e-tratamento.jpg",900,600,false],"2048x2048":["https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2025\/05\/acaros-em-caes-prevencao-e-tratamento.jpg",900,600,false]},"uagb_author_info":{"display_name":"Tiendanimal","author_link":"https:\/\/www.tiendanimal.pt\/blog\/author\/lucia\/"},"uagb_comment_info":0,"uagb_excerpt":"Est\u00e1 preocupado com o facto de o seu c\u00e3o ter \u00e1caros? Descubra como reconhecer, prevenir e eliminar estes parasitas inc\u00f3modos. Um guia completo com conselhos de especialistas.","_links":{"self":[{"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/posts\/11460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/comments?post=11460"}],"version-history":[{"count":10,"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/posts\/11460\/revisions"}],"predecessor-version":[{"id":11471,"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/posts\/11460\/revisions\/11471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/media\/11461"}],"wp:attachment":[{"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/media?parent=11460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/categories?post=11460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/tags?post=11460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}