                {"id":4716,"date":"2025-12-11T09:24:09","date_gmt":"2025-12-11T09:24:09","guid":{"rendered":"https:\/\/www.tiendanimal.pt\/blog\/?p=4716"},"modified":"2025-12-11T09:24:11","modified_gmt":"2025-12-11T09:24:11","slug":"o-chocolate-faz-mal-aos-caes","status":"publish","type":"post","link":"https:\/\/www.tiendanimal.pt\/blog\/o-chocolate-faz-mal-aos-caes\/","title":{"rendered":"O que fazer se o seu c\u00e3o comer chocolate e como reagir?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.tiendanimal.pt\/blog\/o-chocolate-faz-mal-aos-caes\/#Por_que_o_chocolate_e_perigoso_para_os_caes\" >Por que o chocolate \u00e9 perigoso para os c\u00e3es?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.tiendanimal.pt\/blog\/o-chocolate-faz-mal-aos-caes\/#O_que_acontece_se_um_cao_comer_chocolate\" >O que acontece se um c\u00e3o comer chocolate?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.tiendanimal.pt\/blog\/o-chocolate-faz-mal-aos-caes\/#O_que_devo_fazer_se_o_meu_cao_comer_chocolate\" >O que devo fazer se o meu c\u00e3o comer chocolate?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.tiendanimal.pt\/blog\/o-chocolate-faz-mal-aos-caes\/#Como_pode_evitar_que_o_seu_cao_coma_chocolate\" >Como pode evitar que o seu c\u00e3o coma chocolate?<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>O chocolate \u00e9 uma das guloseimas mais saborosas para os humanos, mas sabia que pode ser extremamente <strong>perigoso <\/strong>para os c\u00e3es? Embora dar um peda\u00e7o de chocolate ao seu animal de estima\u00e7\u00e3o possa parecer inofensivo, este alimento cont\u00e9m subst\u00e2ncias que o organismo deles n\u00e3o consegue digerir adequadamente, representando um risco para a sa\u00fade.<\/p>\n\n\n\n<p>Neste artigo<strong>, <\/strong>explicaremos <strong>por que o chocolate pode ser t\u00f3xico para os c\u00e3es, <\/strong>o que deve fazer em caso de emerg\u00eancia e como evitar surpresas desagrad\u00e1veis. Vamos come\u00e7ar!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Por_que_o_chocolate_e_perigoso_para_os_caes\"><\/span>Por que o chocolate \u00e9 perigoso para os c\u00e3es?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O chocolate \u00e9 uma guloseima para n\u00f3s, mas pode causar s\u00e9rios problemas para os c\u00e3es. Por qu\u00ea? Porque cont\u00e9m uma subst\u00e2ncia chamada <strong>teobromina<\/strong>, um composto que os seres humanos podem<strong> <\/strong>digerir facilmente, mas os c\u00e3es <strong>digerem muito lentamente<\/strong>. Isso leva \u00e0 sua acumula\u00e7\u00e3o no organismo e, se a quantidade for grande o suficiente, pode tornar-se t\u00f3xico.<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td><style>.ds-icon-mobile{display:none;}@media screen and (max-width: 767px) {.ds-icon-desktop{display:none;}.ds-icon-mobile{display:inline;}}<\/style><span style=\"color:#78b800\"><svg class=\"bi d-none d-sm-inline-block d-md-inline-block d-lg-inline-block d-xl-inline-block ds-icon-desktop\" width=\"35\" height=\"35\" fill=\"#78b800\"><use xlink:href=\"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#question-circle\"\/><\/svg><svg class=\"bi d-inline-block d-sm-none d-md-none d-lg-none d-xl-none ds-icon-mobile\" width=\"35\" height=\"35\" fill=\"#78b800\"><use xlink:href=\"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#question-circle\"\/><\/svg><\/span><\/td><td><strong>Todos os tipos de chocolate s\u00e3o igualmente perigosos? <\/strong>N\u00e3o, nem todos os tipos de chocolate s\u00e3o igualmente perigosos. <strong>O chocolate preto <\/strong>e o chocolate de cobertura s\u00e3o os mais t\u00f3xicos devido ao<strong> <\/strong>seu alto <strong>teor de teobromina<\/strong>, enquanto <strong>o chocolate de leite <\/strong>tem uma concentra\u00e7\u00e3o menor, mas ainda \u00e9 perigoso se consumido em grandes quantidades. <strong>O chocolate branco <\/strong>cont\u00e9m menos teobromina, mas ainda \u00e9 prejudicial<strong>. Nenhum tipo de chocolate \u00e9 seguro para os c\u00e3es.<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>A intoxica\u00e7\u00e3o por chocolate em c\u00e3es \u00e9 um dos<\/em><strong><em> <\/em><\/strong><em>casos mais<\/em><strong><em> comuns de intoxica\u00e7\u00e3o <\/em><\/strong><em>tratados em hospitais veterin\u00e1rios, especialmente durante ocasi\u00f5es especiais, como <\/em><strong><em>anivers\u00e1rios e Natal.<\/em><\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"has-background\" style=\"background-color:#e6f5db\">Se quiser garantir a seguran\u00e7a do seu animal de estima\u00e7\u00e3o, consulte <strong>a lista completa de alimentos proibidos <\/strong>para saber mais sobre <strong>o <a href=\"https:\/\/www.tiendanimal.pt\/blog\/alimentos-que-os-caes-nao-podem-comer\/\">que os c\u00e3es n\u00e3o podem comer<\/a><\/strong>. Cuide da sa\u00fade deles!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_que_acontece_se_um_cao_comer_chocolate\"><\/span>O que acontece se um c\u00e3o comer chocolate?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Se o seu c\u00e3o comer chocolate, \u00e9 normal e completamente compreens\u00edvel ficar preocupado. Este alimento pode ser <strong>muito perigoso para a sa\u00fade deles<\/strong>. Os efeitos dependem da quantidade consumida, do tipo de chocolate e do tamanho do c\u00e3o, mas mesmo uma pequena quantidade pode causar problemas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Poss\u00edveis sintomas<\/h3>\n\n\n\n<p>Os sintomas de intoxica\u00e7\u00e3o por chocolate geralmente aparecem dentro de<strong> 4 a 12 horas <\/strong>ap\u00f3s a ingest\u00e3o. Abaixo est\u00e3o os sintomas mais comuns:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>V\u00f3mitos e diarreia: <\/strong>estes s\u00e3o os primeiros sinais de alerta e ocorrem quando o corpo tenta expelir o chocolate.<\/li>\n\n\n\n<li><strong>Hiperatividade e tremores: <\/strong>a teobromina tem um efeito estimulante e pode deixar o seu c\u00e3o inquieto ou ansioso.<\/li>\n\n\n\n<li><strong>Aumento da mic\u00e7\u00e3o e da sede: <\/strong>o seu c\u00e3o pode beber mais \u00e1gua e urinar com mais frequ\u00eancia.<\/li>\n\n\n\n<li><strong>Problemas card\u00edacos: <\/strong>a acumula\u00e7\u00e3o de teobromina pode levar a batimentos card\u00edacos acelerados ou at\u00e9 mesmo arritmia.<\/li>\n\n\n\n<li><strong>Convuls\u00f5es e perda de consci\u00eancia: <\/strong>em casos graves, a intoxica\u00e7\u00e3o pode<em> <\/em>levar a convuls\u00f5es, fal\u00eancia de m\u00faltiplos \u00f3rg\u00e3os ou at\u00e9 mesmo \u00e0 morte.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">A gravidade depende do peso do c\u00e3o?<\/h3>\n\n\n\n<p>Sim, <strong>o tamanho do c\u00e3o <\/strong>\u00e9 importante. Por exemplo, um c\u00e3o pequeno pode sofrer uma intoxica\u00e7\u00e3o grave com apenas um pequeno peda\u00e7o de chocolate preto, enquanto um c\u00e3o grande precisaria comer mais para ter um efeito semelhante.<\/p>\n\n\n\n<p>Tamb\u00e9m \u00e9 importante observar <strong>o tipo de chocolate <\/strong>que o c\u00e3o ingeriu. Enquanto o chocolate branco cont\u00e9m menos teobromina, o chocolate ao leite e o chocolate amargo s\u00e3o mais perigosos para a sa\u00fade dos animais.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td><style>.ds-icon-mobile{display:none;}@media screen and (max-width: 767px) {.ds-icon-desktop{display:none;}.ds-icon-mobile{display:inline;}}<\/style><span style=\"color:#78b800\"><svg class=\"bi d-none d-sm-inline-block d-md-inline-block d-lg-inline-block d-xl-inline-block ds-icon-desktop\" width=\"35\" height=\"35\" fill=\"#78b800\"><use xlink:href=\"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#exclamation-triangle\"\/><\/svg><svg class=\"bi d-inline-block d-sm-none d-md-none d-lg-none d-xl-none ds-icon-mobile\" width=\"35\" height=\"35\" fill=\"#78b800\"><use xlink:href=\"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/plugins\/ds-icons\/bootstrap-icons\/bootstrap-icons.svg#exclamation-triangle\"\/><\/svg><\/span><\/td><td>No entanto<strong>, independentemente do tamanho do c\u00e3o ou do tipo de chocolate, qualquer c\u00e3o pode ser prejudicado se comer chocolate. <\/strong>Portanto, \u00e9 importante lembrar que os c\u00e3es n\u00e3o podem comer chocolate.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_que_devo_fazer_se_o_meu_cao_comer_chocolate\"><\/span>O que devo fazer se o meu c\u00e3o comer chocolate?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Se suspeitar ou souber que o seu c\u00e3o comeu chocolate, <strong>deve lev\u00e1-lo imediatamente ao veterin\u00e1rio<\/strong>. Trata-se de <strong>uma emerg\u00eancia<\/strong>, pois se o chocolate for removido do seu corpo dentro de uma hora, os efeitos da intoxica\u00e7\u00e3o ser\u00e3o menos graves.\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>IMPORTANTE<\/strong>: <strong>N\u00e3o tente induzir o v\u00f3mito sem orienta\u00e7\u00e3o profissional. <\/strong>Embora essa seja uma medida comum, ela deve ser feita sob a supervis\u00e3o de um veterin\u00e1rio para evitar complica\u00e7\u00f5es, como aspira\u00e7\u00e3o para os pulm\u00f5es.<\/p>\n<\/blockquote>\n\n\n\n<p>No hospital veterin\u00e1rio, o tratamento depender\u00e1 da quantidade de chocolate que o seu c\u00e3o comeu e dos sintomas que aparecem. Um dos primeiros passos \u00e9, muitas vezes, <strong>lavar <\/strong>o est\u00f4mago para remover quaisquer fragmentos de chocolate antes que possam causar mais danos ao organismo.<\/p>\n\n\n\n<p>Em todos os casos<strong>, <\/strong>deve <strong>manter <\/strong>todos os<strong> <\/strong>alimentos que contenham <strong>chocolate fora do alcance <\/strong>do seu c\u00e3o e <strong>observar o seu comportamento <\/strong>para detetar os sintomas acima mencionados. <strong>Tenha em aten\u00e7\u00e3o que os c\u00e3es n\u00e3o podem comer chocolate.&nbsp;<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_pode_evitar_que_o_seu_cao_coma_chocolate\"><\/span>Como pode evitar que o seu c\u00e3o coma chocolate?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Guarde o chocolate <\/strong>em locais onde os c\u00e3es n\u00e3o tenham acesso, como arm\u00e1rios altos ou gavetas trancadas.<\/li>\n\n\n\n<li>Durante feriados como <strong>o Natal ou anivers\u00e1rios<\/strong>, o chocolate est\u00e1 frequentemente presente em todo o lado. N\u00e3o deixe chocolate na mesa de caf\u00e9 ou ao alcance do seu c\u00e3o. Al\u00e9m disso, lembre <strong>os seus convidados <\/strong>para n\u00e3o darem chocolate ao seu c\u00e3o, mesmo que seja apenas um pequeno peda\u00e7o. No pr\u00f3ximo artigo<strong>, encontrar\u00e1 mais <a href=\"https:\/\/www.tiendanimal.pt\/blog\/os-animais-de-estimacao-nas-festas\/\">dicas para cuidar do seu animal de estima\u00e7\u00e3o durante a \u00e9poca de Natal<\/a><\/strong>.<\/li>\n\n\n\n<li>Deve <strong>ensinar o seu c\u00e3o <\/strong>a comer apenas o que lhe d\u00e1. Isto n\u00e3o s\u00f3 impede o seu c\u00e3o de comer chocolate, como tamb\u00e9m <strong>o protege de outros alimentos perigosos.<\/strong><\/li>\n\n\n\n<li>\u00c0s vezes, <strong>as crian\u00e7as <\/strong>podem querer gentilmente partilhar o chocolate com o c\u00e3o. Explique-lhes que o chocolate pode ser prejudicial para os c\u00e3es.<\/li>\n\n\n\n<li>Se quiser dar ao seu c\u00e3o algo saboroso, escolha <strong><a href=\"https:\/\/www.tiendanimal.pt\/caes\/snacks\/\" target=\"_blank\" rel=\"noreferrer noopener\">snacks para c\u00e3es<\/a><\/strong>. Na Tiendanimal, encontrar\u00e1 muitas <strong>op\u00e7\u00f5es deliciosas e completamente seguras <\/strong>para c\u00e3es.<\/li>\n<\/ul>\n\n\n  <style>\n  .product-container{\n    cursor:pointer;\n  }\n  a.producto-titulo{\n    font-size: 13px;line-height: 1.2;height: 62px;margin-bottom: 12px;color: #575757;font-weight:400;display:inline-block;overflow:hidden;font-family: \"Poppins\", sans-serif;\n  }\n  .producto .product-container img{\n    max-height: 126px;\n    width: auto;\n    height: auto;\n  }\n  @media (max-width: 480px){\n    a.producto-titulo{\n        font-size: 16px;\n        line-height: 1.3;\n    }\n  }\n  <\/style>\n  <div class=\"clearfix\"><\/div>\n    <div id=\"external-products-57646\" class=\"row external-products producto\" style=\"width:100%; margin:0 auto;\"><div itemprop=\"offers\" itemscope itemtype=\"http:\/\/schema.org\/Offer\" class=\"product-container\" style=\"width:19.4%;margin:0 auto;display:inline-block;\" onclick=\"dataLayer.push({'event':'crosseling_product_click', 'event_name':'crosseling_product_click', 'label':'body', 'link_url':'https:\/\/www.tiendanimal.pt\/150-g-criadores-biscoitos-de-maca-para-caes\/CRD31276.html', 'category':'Recompensas e educa\u00e7\u00e3o', 'product_name':'150 g Criadores Biscoitos de ma\u00e7\u00e3 para c\u00e3es'});window.open('https:\/\/www.tiendanimal.pt\/150-g-criadores-biscoitos-de-maca-para-caes\/CRD31276.html');\">\n      <img decoding=\"async\" src=\"https:\/\/www.tiendanimal.pt\/on\/demandware.static\/-\/Sites-kiwoko-master-catalog\/default\/dw70df77f5\/images\/snack_perros_criadores_bocaditos_manzana_CRD31276.jpg\" alt=\"150 g Criadores Biscoitos de ma\u00e7\u00e3 para c\u00e3es\" width=\"90%\" \/><a href=\"https:\/\/www.tiendanimal.pt\/150-g-criadores-biscoitos-de-maca-para-caes\/CRD31276.html\" itemprop=\"name\" class=\"producto-titulo\" data-test=\"test\" target=\"_blank\">150 g Criadores Biscoitos de ma\u00e7\u00e3 para c\u00e3es<\/a>\n      <button class=\"producto-boton\" style=\"width:100%;border-radius:3px;padding:5px;\">Ver produto<\/button><\/div>\n      <div itemprop=\"offers\" itemscope itemtype=\"http:\/\/schema.org\/Offer\" class=\"product-container\" style=\"width:19.4%;margin:0 auto;display:inline-block;\" onclick=\"dataLayer.push({'event':'crosseling_product_click', 'event_name':'crosseling_product_click', 'label':'body', 'link_url':'https:\/\/www.tiendanimal.pt\/300-g-criadores-biscoitos-semi-humidos-de-frango-para-caes\/CRD58525.html', 'category':'Semi h\u00famidos', 'product_name':'300 g Criadores Biscoitos Semi-h\u00famidos de frango para c\u00e3es'});window.open('https:\/\/www.tiendanimal.pt\/300-g-criadores-biscoitos-semi-humidos-de-frango-para-caes\/CRD58525.html');\">\n      <img decoding=\"async\" src=\"https:\/\/www.tiendanimal.pt\/on\/demandware.static\/-\/Sites-kiwoko-master-catalog\/default\/dwfeaf571e\/images\/snacks_perro_Criadores_snack_humedo_bocaditos_pollo_para_perros_CRD19623.jpg\" alt=\"300 g Criadores Biscoitos Semi-h\u00famidos de frango para c\u00e3es\" width=\"90%\" \/><a href=\"https:\/\/www.tiendanimal.pt\/300-g-criadores-biscoitos-semi-humidos-de-frango-para-caes\/CRD58525.html\" itemprop=\"name\" class=\"producto-titulo\" data-test=\"test\" target=\"_blank\">300 g Criadores Biscoitos Semi-h\u00famidos de frango para c\u00e3es<\/a>\n      <button class=\"producto-boton\" style=\"width:100%;border-radius:3px;padding:5px;\">Ver produto<\/button><\/div>\n      <div itemprop=\"offers\" itemscope itemtype=\"http:\/\/schema.org\/Offer\" class=\"product-container\" style=\"width:19.4%;margin:0 auto;display:inline-block;\" onclick=\"dataLayer.push({'event':'crosseling_product_click', 'event_name':'crosseling_product_click', 'label':'body', 'link_url':'https:\/\/www.tiendanimal.pt\/200-g-criadores-snack-semi-humido-biscoitos-de-calcio-para-caes\/CRD34550.html', 'category':'Snacks para cachorros', 'product_name':'200 g Criadores Snack Semi-h\u00famido Biscoitos de c\u00e1lcio para c\u00e3es'});window.open('https:\/\/www.tiendanimal.pt\/200-g-criadores-snack-semi-humido-biscoitos-de-calcio-para-caes\/CRD34550.html');\">\n      <img decoding=\"async\" src=\"https:\/\/www.tiendanimal.pt\/on\/demandware.static\/-\/Sites-kiwoko-master-catalog\/default\/dwcbc18913\/images\/snacks_perro_Criadores_snack_con_calcio_para_perros_cachorros_CRD34550.jpg\" alt=\"200 g Criadores Snack Semi-h\u00famido Biscoitos de c\u00e1lcio para c\u00e3es\" width=\"90%\" \/><a href=\"https:\/\/www.tiendanimal.pt\/200-g-criadores-snack-semi-humido-biscoitos-de-calcio-para-caes\/CRD34550.html\" itemprop=\"name\" class=\"producto-titulo\" data-test=\"test\" target=\"_blank\">200 g Criadores Snack Semi-h\u00famido Biscoitos de c\u00e1lcio para c\u00e3es<\/a>\n      <button class=\"producto-boton\" style=\"width:100%;border-radius:3px;padding:5px;\">Ver produto<\/button><\/div>\n      <div itemprop=\"offers\" itemscope itemtype=\"http:\/\/schema.org\/Offer\" class=\"product-container\" style=\"width:19.4%;margin:0 auto;display:inline-block;\" onclick=\"dataLayer.push({'event':'crosseling_product_click', 'event_name':'crosseling_product_click', 'label':'body', 'link_url':'https:\/\/www.tiendanimal.pt\/200-g-criadores-snack-semi-humido-biscoitos-de-cordeiro-para-caes\/CRD20151.html', 'category':'Semi h\u00famidos', 'product_name':'200 g Criadores Snack Semi-h\u00famido Biscoitos de cordeiro para c\u00e3es'});window.open('https:\/\/www.tiendanimal.pt\/200-g-criadores-snack-semi-humido-biscoitos-de-cordeiro-para-caes\/CRD20151.html');\">\n      <img decoding=\"async\" src=\"https:\/\/www.tiendanimal.pt\/on\/demandware.static\/-\/Sites-kiwoko-master-catalog\/default\/dwc3ff9b10\/images\/snacks_perro_Criadores_snack_humedo_corazones_cordero_perros_CRD20151_1.jpg\" alt=\"200 g Criadores Snack Semi-h\u00famido Biscoitos de cordeiro para c\u00e3es\" width=\"90%\" \/><a href=\"https:\/\/www.tiendanimal.pt\/200-g-criadores-snack-semi-humido-biscoitos-de-cordeiro-para-caes\/CRD20151.html\" itemprop=\"name\" class=\"producto-titulo\" data-test=\"test\" target=\"_blank\">200 g Criadores Snack Semi-h\u00famido Biscoitos de cordeiro para c\u00e3es<\/a>\n      <button class=\"producto-boton\" style=\"width:100%;border-radius:3px;padding:5px;\">Ver produto<\/button><\/div>\n      <div itemprop=\"offers\" itemscope itemtype=\"http:\/\/schema.org\/Offer\" class=\"product-container\" style=\"width:19.4%;margin:0 auto;display:inline-block;\" onclick=\"dataLayer.push({'event':'crosseling_product_click', 'event_name':'crosseling_product_click', 'label':'body', 'link_url':'https:\/\/www.tiendanimal.pt\/150-g-criadores-biscoitos-hipoalergenicos-para-caes-\/CRD31247.html', 'category':'Recompensas e educa\u00e7\u00e3o', 'product_name':'150 g Criadores Biscoitos Hipoalerg\u00e9nicos para c\u00e3es'});window.open('https:\/\/www.tiendanimal.pt\/150-g-criadores-biscoitos-hipoalergenicos-para-caes-\/CRD31247.html');\">\n      <img decoding=\"async\" src=\"https:\/\/www.tiendanimal.pt\/on\/demandware.static\/-\/Sites-kiwoko-master-catalog\/default\/dw9429ab7b\/images\/criadores_snack_perros_CRD31247.jpg.jpg\" alt=\"150 g Criadores Biscoitos Hipoalerg\u00e9nicos para c\u00e3es\" width=\"90%\" \/><a href=\"https:\/\/www.tiendanimal.pt\/150-g-criadores-biscoitos-hipoalergenicos-para-caes-\/CRD31247.html\" itemprop=\"name\" class=\"producto-titulo\" data-test=\"test\" target=\"_blank\">150 g Criadores Biscoitos Hipoalerg\u00e9nicos para c\u00e3es<\/a>\n      <button class=\"producto-boton\" style=\"width:100%;border-radius:3px;padding:5px;\">Ver produto<\/button><\/div>\n      <\/div>\n    <br>\n    <div class=\"clearfix\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>N\u00e3o \u00e9 s\u00f3 o chocolate que \u00e9 perigoso. <strong>Bolachas, bolos ou mesmo cereais <\/strong>podem conter chocolate e ser prejudiciais para os c\u00e3es. <strong>\u00c9<\/strong> melhor <strong>n\u00e3o alimentar os c\u00e3es com<\/strong> <strong>comida humana <\/strong>que n\u00e3o \u00e9 adequada para eles.<\/li>\n<\/ul>\n\n\n\n<p>O chocolate n\u00e3o \u00e9 bom para os c\u00e3es, mesmo que nos pare\u00e7a saboroso. Embora possamos pensar que um pequeno peda\u00e7o n\u00e3o lhes far\u00e1 mal, <strong>pode ser muito perigoso para a sa\u00fade deles.<\/strong><\/p>\n\n\n\n<p>Mantenha sempre o chocolate fora do alcance do seu c\u00e3o e escolha snacks seguros para ele. Em caso de acidente<strong>, aja rapidamente e confie no seu veterin\u00e1rio<\/strong>: ele est\u00e1 sempre pronto para ajud\u00e1-lo a cuidar do seu melhor amigo.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Leia os seguintes artigos para obter mais dicas sobre a alimenta\u00e7\u00e3o do seu c\u00e3o:<\/p>\n\n\n        <div class=\"grid\">\n        <div class=\"grid-sizer\"><\/div>\n                <a href=\"https:\/\/www.tiendanimal.pt\/blog\/comida-caseira-para-caes-ou-racao\/\" class=\"ds-analytics-blog-related-posts\" title=\"\u00a0O que \u00e9 melhor para os c\u00e3es: ra\u00e7\u00e3o seca ou comida caseira\/natural?\">\n            <div class=\"grid-item\">\n                <div style=\"background: url(https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2016\/04\/o-que-e-melhor-para-os-caes-racao-seca-ou-comida-caseira-natural-768x512.jpg);background-size:cover;\n                background-position: center;background-repeat: no-repeat;height:230px;\">\n                <\/div>\n                <p class=\"slider-caption\">\u00a0O que \u00e9 melhor para os c\u00e3es: ra\u00e7\u00e3o seca ou comida caseira\/natural?<\/p>\n            <\/div>\n        <\/a>\n                <a href=\"https:\/\/www.tiendanimal.pt\/blog\/e-possivel-misturar-a-dieta-barf-com-racao\/\" class=\"ds-analytics-blog-related-posts\" title=\"\u00c9 poss\u00edvel misturar a dieta BARF com ra\u00e7\u00e3o?\">\n            <div class=\"grid-item\">\n                <div style=\"background: url(https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2025\/05\/dieta-mista-de-barf-e-racao-768x512.jpg);background-size:cover;\n                background-position: center;background-repeat: no-repeat;height:230px;\">\n                <\/div>\n                <p class=\"slider-caption\">\u00c9 poss\u00edvel misturar a dieta BARF com ra\u00e7\u00e3o?<\/p>\n            <\/div>\n        <\/a>\n                <a href=\"https:\/\/www.tiendanimal.pt\/blog\/alergias-e-intolerancias-alimentares-em-caes\/\" class=\"ds-analytics-blog-related-posts\" title=\"Alergias e intoler\u00e2ncias alimentares nos c\u00e3es: o que s\u00e3o, como as detetar e conselhos\">\n            <div class=\"grid-item\">\n                <div style=\"background: url(https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2024\/04\/alergias-e-intolerancias-alimentares-em-caes-768x512.jpg);background-size:cover;\n                background-position: center;background-repeat: no-repeat;height:230px;\">\n                <\/div>\n                <p class=\"slider-caption\">Alergias e intoler\u00e2ncias alimentares nos c\u00e3es: o que s\u00e3o, como as detetar e conselhos<\/p>\n            <\/div>\n        <\/a>\n            <\/div>\n    <script src=\"https:\/\/www.tiendanimal.pt\/blog\/wp-content\/themes\/astra-child-ta\/assets\/js\/masonry.pkgd.js\"><\/script>\n    <script type=\"text\/javascript\">\n        var $grid = jQuery('.grid').masonry({\n            itemSelector: '.grid-item',\n            percentPosition: true,\n            columnWidth: '.grid-sizer'\n        });\n    <\/script>\n    \n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#e6f5db\">Se precisar de algo para o seu animal de estima\u00e7\u00e3o, na <a href=\"https:\/\/www.tiendanimal.pt\/\"><strong>Tiendanimal<\/strong> <\/a>queremos ajud\u00e1-lo. <strong><a href=\"https:\/\/www.tiendanimal.pt\/nossas-lojas?showMap=true&amp;horizontalView=true&amp;isForm=true\">Encontre a sua loja mais pr\u00f3xima<\/a><\/strong> ou se preferir, fa\u00e7a a sua encomenda na nossa loja online especializada em produtos para animais de estima\u00e7\u00e3o, e n\u00e3o perca as nossas <strong><a href=\"https:\/\/www.tiendanimal.pt\/promocoes\/\">promo\u00e7\u00f5es!<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saiba por que o chocolate \u00e9 perigoso para os c\u00e3es, o que fazer se eles comerem chocolate e como prevenir a intoxica\u00e7\u00e3o. Cuide da sa\u00fade do seu c\u00e3o com estas dicas.<\/p>\n","protected":false},"author":40,"featured_media":4738,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3,5],"tags":[209],"class_list":["post-4716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caes","category-alimentacao-caes","tag-alimentacao","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2022\/01\/O-chocolate-faz-ma-aos-caes_.jpg",900,600,false],"thumbnail":["https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2022\/01\/O-chocolate-faz-ma-aos-caes_-150x150.jpg",150,150,true],"medium":["https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2022\/01\/O-chocolate-faz-ma-aos-caes_-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2022\/01\/O-chocolate-faz-ma-aos-caes_-768x512.jpg",768,512,true],"large":["https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2022\/01\/O-chocolate-faz-ma-aos-caes_.jpg",900,600,false],"1536x1536":["https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2022\/01\/O-chocolate-faz-ma-aos-caes_.jpg",900,600,false],"2048x2048":["https:\/\/www.tiendanimal.pt\/blog\/wp-content\/uploads\/2022\/01\/O-chocolate-faz-ma-aos-caes_.jpg",900,600,false]},"uagb_author_info":{"display_name":"Tiendanimal","author_link":"https:\/\/www.tiendanimal.pt\/blog\/author\/lucia\/"},"uagb_comment_info":1,"uagb_excerpt":"Saiba por que o chocolate \u00e9 perigoso para os c\u00e3es, o que fazer se eles comerem chocolate e como prevenir a intoxica\u00e7\u00e3o. Cuide da sa\u00fade do seu c\u00e3o com estas dicas.","_links":{"self":[{"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/posts\/4716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/comments?post=4716"}],"version-history":[{"count":12,"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/posts\/4716\/revisions"}],"predecessor-version":[{"id":12875,"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/posts\/4716\/revisions\/12875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/media\/4738"}],"wp:attachment":[{"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/media?parent=4716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/categories?post=4716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tiendanimal.pt\/blog\/wp-json\/wp\/v2\/tags?post=4716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}